{"id":53,"count":1,"description":"","link":"https:\/\/livingfrompassion2profits.com\/cci\/tenders-category\/etudes-conseil\/","name":"\u00c9tudes \/ Conseil","slug":"etudes-conseil","taxonomy":"tenders-category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/livingfrompassion2profits.com\/cci\/wp-json\/wp\/v2\/tenders-category\/53","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/livingfrompassion2profits.com\/cci\/wp-json\/wp\/v2\/tenders-category"}],"about":[{"href":"https:\/\/livingfrompassion2profits.com\/cci\/wp-json\/wp\/v2\/taxonomies\/tenders-category"}],"wp:post_type":[{"href":"https:\/\/livingfrompassion2profits.com\/cci\/wp-json\/wp\/v2\/cci-public-tenders?tenders-category=53"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}